{"id":613,"date":"2016-03-11T10:58:11","date_gmt":"2016-03-11T13:58:11","guid":{"rendered":"https:\/\/www.arte.unicen.edu.ar\/indees\/?p=613"},"modified":"2016-03-11T10:58:11","modified_gmt":"2016-03-11T13:58:11","slug":"el-indees-miembro-de-la-oistat-organizacion-internacional-de-escenografos-arquitectos-y-tecnicos-de-teatro","status":"publish","type":"post","link":"https:\/\/www.arte.unicen.edu.ar\/indees\/el-indees-miembro-de-la-oistat-organizacion-internacional-de-escenografos-arquitectos-y-tecnicos-de-teatro\/","title":{"rendered":"El INDEES miembro de la OISTAT (Organizaci\u00f3n Internacional de Escen\u00f3grafos, Arquitectos y T\u00e9cnicos de Teatro)"},"content":{"rendered":"<p style=\"text-align: justify;\">El Instituto de Estudios Escenogr\u00e1ficos en Artes Esc\u00e9nicas y Audiovisuales (perteneciente al Centro de Investigaciones Dram\u00e1ticas de la Facultad de Arte de la UNICEN) ha logrado constituirse en miembro asociado de la Organizaci\u00f3n Internacional de Escen\u00f3grafos, T\u00e9cnicos y Arquitectos de Teatro, (OISTAT), la organizaci\u00f3n m\u00e1s importante y con mayor visibilidad y proyecci\u00f3n a nivel internacional dedicada al \u00e1mbito de la escenograf\u00eda.<\/p>\n<p style=\"text-align: justify;\">La OISTAT es una organizaci\u00f3n no gubernamental, reconocida por la UNESCO, que genera, promueve y mantiene una red global de organizaciones, institutos, profesionales y educadores en m\u00e1s de 50 pa\u00edses y da fomento al desarrollo de la escenograf\u00eda y el vestuario en todo el mundo, a trav\u00e9s de la organizaci\u00f3n de eventos, proyectos editoriales, congresos, comisiones de trabajo. Adem\u00e1s permite la comunicaci\u00f3n permanente de conocimientos y el intercambio de innovaciones y estudios, para fomentar la colaboraci\u00f3n internacional en el desarrollo de la escenograf\u00eda, puesta en escena y arquitectura teatral.<\/p>\n<p style=\"text-align: justify;\">Como miembro asociado de la OISTAT, el INDEES se nutre de nuevos impulsos y desaf\u00edos, ya que lo encuentra inserto en una red internacional de intercambio y promoci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Estudios Escenogr\u00e1ficos en Artes Esc\u00e9nicas y Audiovisuales (perteneciente al Centro de Investigaciones Dram\u00e1ticas de la Facultad de Arte de la UNICEN) ha logrado constituirse en miembro&#8230; <\/p>\n<div align=\"right\"><a href=\"https:\/\/www.arte.unicen.edu.ar\/indees\/el-indees-miembro-de-la-oistat-organizacion-internacional-de-escenografos-arquitectos-y-tecnicos-de-teatro\/\" class=\"read-more\"><span class=\"fa fa-hand-o-right\"><\/span> Leer m\u00e1s&#8230;<\/a><\/div>\n","protected":false},"author":1,"featured_media":617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[43,58,84,90],"class_list":["post-613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-escenografia","tag-indees","tag-miembro-asociado","tag-oistat"],"_links":{"self":[{"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/posts\/613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":0,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/posts\/613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/media?parent=613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/categories?post=613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/indees\/wp-json\/wp\/v2\/tags?post=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}