{"id":24283,"date":"2022-07-05T12:26:22","date_gmt":"2022-07-05T15:26:22","guid":{"rendered":"http:\/\/www.arte.unicen.edu.ar\/cdab\/?p=24283"},"modified":"2022-07-19T13:12:47","modified_gmt":"2022-07-19T16:12:47","slug":"cdab-vinculo-fundacion-espigas-donacion-de-publicaciones","status":"publish","type":"post","link":"https:\/\/www.arte.unicen.edu.ar\/cdab\/cdab-vinculo-fundacion-espigas-donacion-de-publicaciones\/","title":{"rendered":"El CDAB establece un v\u00ednculo con la Fundaci\u00f3n Espigas y recibe una significativa donaci\u00f3n de sus publicaciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el marco de las gestiones realizadas por el <strong>Centro de Documentaci\u00f3n Audiovisual y Biblioteca (CDAB)<\/strong> de la <a rel=\"noreferrer noopener\" aria-label=\"Facultad de Arte (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.arte.unicen.edu.ar\" target=\"_blank\">Facultad de Arte<\/a> con el objetivo de integrar redes de cooperaci\u00f3n y archivo y generar v\u00ednculos institucionales estrat\u00e9gicos que permitan establecer donaciones de materiales y promover el intercambio de conocimientos y recursos, desde hace algunos meses trabajamos en este sentido con la <a rel=\"noreferrer noopener\" aria-label=\"Fundaci\u00f3n Espigas (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\" target=\"_blank\">Fundaci\u00f3n Espigas<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" aria-label=\"Fundaci\u00f3n Espigas (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\" target=\"_blank\">Espigas<\/a> y su Centro de Documentaci\u00f3n para la Historia de la Artes Visuales en la Argentina se crean en 1993 con el fin de hacer un aporte a la profesionalizaci\u00f3n del medio art\u00edstico. Su misi\u00f3n es reunir toda la documentaci\u00f3n referida al arte argentino y latinoamericano, y las manifestaciones art\u00edsticas extranjeras vinculadas al pa\u00eds y la regi\u00f3n. Con la colaboraci\u00f3n constante de donantes y socios, <a rel=\"noreferrer noopener\" aria-label=\"Espigas (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\" target=\"_blank\">Espigas<\/a> conserva y da acceso a un importante acervo bibliogr\u00e1fico y archiv\u00edstico que es actualmente consultado por especialistas, instituciones p\u00fablicas y privadas, y p\u00fablico en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta colaboraci\u00f3n institucional mutua, que en primera instancia implic\u00f3 la recepci\u00f3n de algunas publicaciones editadas por <a rel=\"noreferrer noopener\" aria-label=\"Espigas (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\" target=\"_blank\">Espigas<\/a> y el env\u00edo de materiales de <a rel=\"noreferrer noopener\" aria-label=\"Arte Publicaciones (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.arte.unicen.edu.ar\/artepublicaciones\" target=\"_blank\">Arte Publicaciones<\/a> -sello editorial de la <a rel=\"noreferrer noopener\" aria-label=\"Facultad de Arte (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.arte.unicen.edu.ar\" target=\"_blank\">Facultad de Arte<\/a>-, constituye un primer acercamiento para desarrollar actividades conjuntas a futuro. Una de las pr\u00f3ximas propuestas consistir\u00e1 en una charla abierta a realizarse durante la pr\u00f3xima edici\u00f3n de <a rel=\"noreferrer noopener\" aria-label=\"CDAB en movimiento (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.arte.unicen.edu.ar\/cdab\/enmovimiento\" target=\"_blank\">CDAB en movimiento<\/a> en el mes de septiembre. La actividad propondr\u00e1 un recorrido virtual por la sede de la Fundaci\u00f3n para conocer sus l\u00edneas de trabajo, los modos en que se mantienen accesibles los fondos y colecciones, y qu\u00e9 profesiones y tareas hacen posible el funcionamiento diario del Centro de Estudios Espigas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el <strong>CDAB<\/strong> reafirmamos el compromiso en el campo de la preservaci\u00f3n y la documentaci\u00f3n. La <a rel=\"noreferrer noopener\" aria-label=\"Red Argentina de Acervos Fotogr\u00e1ficos, Audiovisuales y Sonoros (RAAFAS) (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.raafas.net.ar\" target=\"_blank\">Red Argentina de Acervos Fotogr\u00e1ficos, Audiovisuales y Sonoros (RAAFAS)<\/a>, coordinada por el Grupo de trabajo sobre gesti\u00f3n de Documentos Fotogr\u00e1ficos, Sonoros y Audiovisuales (GT-GDFSA), y <a rel=\"noreferrer noopener\" aria-label=\"BiblioCi (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.biblioci.org\" target=\"_blank\">BiblioCi<\/a>, red iberoamericana de unidades de informaci\u00f3n especializadas en cine y medios audiovisuales, son dos espacios que integramos desde 2017 y 2019 respectivamente y dan cuenta de esta apertura que forma parte de la misi\u00f3n del Centro de Documentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n acerca de las publicaciones editadas por la <a rel=\"noreferrer noopener\" aria-label=\"Fundaci\u00f3n Espigas (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\" target=\"_blank\">Fundaci\u00f3n Espigas<\/a> ingresar a: <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.espigas.org.ar\/es\/publicaciones\" target=\"_blank\">www.espigas.org.ar\/es\/publicaciones<\/a><\/p>\n\n\n\n<a href=\"http:\/\/www.arte.unicen.edu.ar\/cdab\/wp-content\/uploads\/2022\/07\/donacion-espigas2022.jpg\" data-fancybox=\"gallery\" data-caption=\"El CDAB establece un v\u00ednculo con la Fundaci\u00f3n Espigas y recibe una significativa donaci\u00f3n de sus publicaciones\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2866\" src=\"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-content\/uploads\/2022\/07\/donacion-espigas2022-322x600.jpg\" alt=\"\" width=\"300\" height=\"560\"\/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las gestiones realizadas por el Centro de Documentaci\u00f3n Audiovisual y Biblioteca (CDAB) de la Facultad de Arte con el objetivo de integrar redes de cooperaci\u00f3n y archivo y generar v\u00ednculos institucionales estrat\u00e9gicos que permitan establecer donaciones de materiales y promover el intercambio de conocimientos y recursos, desde hace algunos meses trabajamos en este sentido con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[214,215,3445,288,294],"class_list":["post-24283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades","tag-cdab","tag-facultad-de-arte","tag-fundacion-espigas","tag-secretaria-de-investigacion-y-posgrado","tag-unicen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/24283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/comments?post=24283"}],"version-history":[{"count":2,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/24283\/revisions"}],"predecessor-version":[{"id":24496,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/24283\/revisions\/24496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/media\/24289"}],"wp:attachment":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/media?parent=24283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/categories?post=24283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/tags?post=24283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}