{"id":20095,"date":"2021-07-08T09:22:21","date_gmt":"2021-07-08T12:22:21","guid":{"rendered":"http:\/\/www.arte.unicen.edu.ar\/cdab\/?p=20095"},"modified":"2021-10-02T18:48:35","modified_gmt":"2021-10-02T21:48:35","slug":"mirar-siguiendo-luz-rdp-presenta-luminar","status":"publish","type":"post","link":"https:\/\/www.arte.unicen.edu.ar\/cdab\/mirar-siguiendo-luz-rdp-presenta-luminar\/","title":{"rendered":"Mirar siguiendo la luz que irradian todas las formas de vida: Ritos de paso presenta &#8220;Luminar&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pasamos un tiempo desconocido, un apocalipsis no imaginado como consecuencia de un virus mortal de alcance mundial y ahora estamos tendiendo puentes en un desaf\u00edo por reinventar la subjetividad porque la  pospandemia ser\u00e1 un proceso largo. Una vez m\u00e1s, las b\u00fasquedas de sentido son las que nos salvan y posibilitan que sigamos pensando(nos) en colectivo. Este <strong>jueves 8 de julio<\/strong> a las <strong>19 hs.<\/strong> se estrena <em>Luminar<\/em>, el segundo cap\u00edtulo de la nueva temporada de <strong>Ritos de paso<\/strong>, la serie audiovisual experimental, colectiva y colaborativa que cuenta con el apoyo de <a rel=\"noreferrer noopener\" href=\"http:\/\/www.arte.unicen.edu.ar\/artepublicaciones\" target=\"_blank\">Arte Publicaciones<\/a>, el <a rel=\"noreferrer noopener\" href=\"http:\/\/www.arte.unicen.edu.ar\/cdab\" target=\"_blank\">CDAB<\/a> y la <a rel=\"noreferrer noopener\" href=\"http:\/\/www.arte.unicen.edu.ar\/secretarias\/investigacion-posgrado\" target=\"_blank\">Secretar\u00eda de Investigaci\u00f3n y Posgrado<\/a> de la <a rel=\"noreferrer noopener\" aria-label=\"Facultad de Arte (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.arte.unicen.edu.ar\" target=\"_blank\">Facultad de Arte<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En continuidad con el solsticio de invierno y las noches largas en sudam\u00e9rica, el cap\u00edtulo problematiza el concepto <em>dar a luz<\/em> o <em>alumbrar<\/em>. En el imaginario com\u00fan est\u00e1 ligado a la maternidad, pero puede relacionarse con el acto de mirar, siguiendo la luz que irradian todas las formas de vida que nos rodean e invitan a cuidarlas. \u00bfC\u00f3mo lo hacemos? Con la palabra, con el lenguaje. Porque yo voy andando y cantando, que es mi modo de alumbrar. Porque entre tantos ojos que miran por una c\u00e1mara buscando captar el aliento que sale alumbrado y visible en los inviernos australes hemos descubierto que las Noches Blancas, son solo una ficci\u00f3n. <em>Luminar<\/em> cuenta con la colaboraci\u00f3n del <em>\u00c1rea de Producci\u00f3n Audiovisual<\/em> de la <a rel=\"noreferrer noopener\" href=\"http:\/\/www.untdf.edu.ar\" target=\"_blank\">Universidad Nacional de Tierra del Fuego, Ant\u00e1rtida e Islas del Atl\u00e1ntico Sur<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Invitamos a visionar esta nueva entrega y seguir los estrenos quincenales en <a href=\"https:\/\/www.artexver.tv\/rdp2-2\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">artexver<\/a> y el <a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/channel\/UC4A6udlDT1SmVyAF-6yxM8w\" target=\"_blank\">canal de YouTube<\/a> de <strong>Ritos de paso<\/strong>.<\/p>\n\n\n\n<div style=\"margin: 30px auto; width: 100%; text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/6xOnZ04VBjk\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"700\" height=\"394\" frameborder=\"0\"><\/iframe>\n<div class=\"container-newsbutton\"><a class=\"cdab-newsbuttonlink\" href=\"https:\/\/www.youtube.com\/channel\/UC4A6udlDT1SmVyAF-6yxM8w\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"cdab-youtube-newsbutton\">RITOS DE PASO<\/div><\/a><a class=\"cdab-newsbuttonlink\" href=\"https:\/\/www.instagram.com\/ritosdepaso\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"margin-left: 50px;\"><div class=\"cdab-instagram-newsbutton\">RITOS DE PASO<\/div><\/a><a class=\"cdab-newsbuttonlink\" href=\"https:\/\/www.artexver.tv\/serie\/ritos-de-paso\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"margin-left: 50px;\"><div class=\"cdab-artexver-newsbutton\"><\/div><\/a><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La coordinaci\u00f3n general del proyecto est\u00e1 a cargo de <strong>Anabel Bonani, Mariano Schettino, Mat\u00edas Petrini<\/strong> y <strong>Claudia C. Speranza<\/strong>. El dise\u00f1o de las piezas gr\u00e1ficas es de <strong>Mariano Schettino<\/strong> y los temas musicales de la serie son de <strong>Agostina Romeo<\/strong>. <em>Luminar<\/em> cont\u00f3 con direcci\u00f3n de <strong>Valentina Fourastie<\/strong> (graduada <a href=\"http:\/\/www.arte.unicen.edu.ar\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"FA (abre en una nueva pesta\u00f1a)\">FA<\/a>, <a rel=\"noreferrer noopener\" aria-label=\"UNICEN (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.unicen.edu.ar\" target=\"_blank\">UNICEN<\/a>) y asistencia de direcci\u00f3n de <strong>Claudia C. Speranza<\/strong>. Los textos corresponden a fragmentos de <em>Noches Blancas<\/em> de Fiodor Dostoievski y escritos de <strong>Valentina Fourastie<\/strong>. Las im\u00e1genes en Ushuaia fueron registradas por <strong>Guido De Paula<\/strong> (@guidogusti) &#8211;<em>\u00c1rea de Producci\u00f3n Audiovisual<\/em> de la <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.untdf.edu.ar\" target=\"_blank\">Universidad Nacional de Tierra del Fuego, Ant\u00e1rtida e Islas del Atl\u00e1ntico Sur<\/a> (@untdfmedios)- y en Tandil por <strong>Valentina Fourastie<\/strong> y <strong>Mart\u00edn Tommasi<\/strong> (drone).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La animaci\u00f3n inicial es de <strong>Mat\u00edas Petrini<\/strong>, la m\u00fasica de <strong>Sabrina Molina<\/strong> (@molinasabrina_) y la voz pertenece a <strong>Tamara Castiglione<\/strong>. El montaje lo realizaron <strong>Nadia Girolami<\/strong> y <strong>Valentina Fourastie<\/strong> y la postproducci\u00f3n de imagen <strong>Nadia Girolami<\/strong> (@nachigirolami). Act\u00faa en este cap\u00edtulo <strong>Luc\u00eda Roldan<\/strong>. El equipo realizador agradece especialmente a su familia y amigxs, a <strong>Juan Pablo Lattanzi<\/strong> y <strong>Guido De Paula<\/strong>, y, a trav\u00e9s de ellos a todxs lxs colegas de la <a rel=\"noreferrer noopener\" aria-label=\"Universidad Nacional de Tierra del Fuego (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.untdf.edu.ar\" target=\"_blank\">Universidad Nacional de Tierra del Fuego<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasamos un tiempo desconocido, un apocalipsis no imaginado como consecuencia de un virus mortal de alcance mundial y ahora estamos tendiendo puentes en un desaf\u00edo por reinventar la subjetividad porque la pospandemia ser\u00e1 un proceso largo. Una vez m\u00e1s, las b\u00fasquedas de sentido son las que nos salvan y posibilitan que sigamos pensando(nos) en colectivo. Este jueves 8 de julio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[292,2534,214,215,2535,288,294],"class_list":["post-20095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades","tag-arte-publicaciones","tag-artexver","tag-cdab","tag-facultad-de-arte","tag-ritos-de-paso","tag-secretaria-de-investigacion-y-posgrado","tag-unicen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/20095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/comments?post=20095"}],"version-history":[{"count":2,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/20095\/revisions"}],"predecessor-version":[{"id":21003,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/posts\/20095\/revisions\/21003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/media\/20413"}],"wp:attachment":[{"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/media?parent=20095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/categories?post=20095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arte.unicen.edu.ar\/cdab\/wp-json\/wp\/v2\/tags?post=20095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}